{"id":15,"count":20,"description":"","link":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/","name":"TP10","slug":"tp10","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TP10 Archive - Stark im Norden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TP10 Archive - Stark im Norden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/\" \/>\n<meta property=\"og:site_name\" content=\"Stark im Norden\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/category\\\/tp10\\\/\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/category\\\/tp10\\\/\",\"name\":\"TP10 Archive - Stark im Norden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/category\\\/tp10\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/category\\\/tp10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TP10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\",\"name\":\"Stark im Norden\",\"description\":\"QM Alt-Hamborn und Marxloh\",\"publisher\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#organization\",\"name\":\"Stark im Norden\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_03.jpg\",\"contentUrl\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_03.jpg\",\"width\":2000,\"height\":1199,\"caption\":\"Stark im Norden\"},\"image\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/du_starkimnorden\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TP10 Archive - Stark im Norden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/","og_locale":"de_DE","og_type":"article","og_title":"TP10 Archive - Stark im Norden","og_url":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/","og_site_name":"Stark im Norden","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/","url":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/","name":"TP10 Archive - Stark im Norden","isPartOf":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/du-starkimnorden.de\/wordpress\/category\/tp10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/du-starkimnorden.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"TP10"}]},{"@type":"WebSite","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#website","url":"https:\/\/du-starkimnorden.de\/wordpress\/","name":"Stark im Norden","description":"QM Alt-Hamborn und Marxloh","publisher":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/du-starkimnorden.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#organization","name":"Stark im Norden","url":"https:\/\/du-starkimnorden.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2023\/04\/Logo_03.jpg","contentUrl":"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2023\/04\/Logo_03.jpg","width":2000,"height":1199,"caption":"Stark im Norden"},"image":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/du_starkimnorden\/"]}]}},"_links":{"self":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/posts?categories=15"},{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/pages?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}