{"id":8059,"date":"2026-04-28T09:18:12","date_gmt":"2026-04-28T07:18:12","guid":{"rendered":"https:\/\/du-starkimnorden.de\/wordpress\/?p=8059"},"modified":"2026-04-28T09:18:15","modified_gmt":"2026-04-28T07:18:15","slug":"am_06","status":"publish","type":"post","link":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/","title":{"rendered":"AM_06"},"content":{"rendered":"<section class=\"ffb-id-68fap06l fg-section fg-text-dark\"><div class=\"fg-container container fg-container-large fg-container-lvl--1 \"><div class=\"fg-row row    \"><div class=\"ffb-id-68fap06m fg-col col-xs-12 col-md-12 fg-text-dark\"><a class=\"ffb-id-9fc75iej  responsive-image-wrapper freshframework-lightbox-image fg-text-dark\" href=\"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2026\/04\/Altmarkt_6.jpg\"><img decoding=\"async\" srcset=\"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2026\/04\/Altmarkt_6.jpg 1772w, https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/freshizer\/0bb1eb92f2b2ce40a987509ff34f7b33_Altmarkt_6-320-c-100.jpg 320w, https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/freshizer\/0bb1eb92f2b2ce40a987509ff34f7b33_Altmarkt_6-768-c-100.jpg 768w, https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/freshizer\/0bb1eb92f2b2ce40a987509ff34f7b33_Altmarkt_6-992-c-100.jpg 992w, https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/freshizer\/0bb1eb92f2b2ce40a987509ff34f7b33_Altmarkt_6-1200-c-100.jpg 1200w\" sizes=\"(max-width: 1772px) 100vw, 1772px\" class=\"fg-image  img-responsive full-width\" src=\"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2026\/04\/Altmarkt_6.jpg\" alt=\"Flyer Altmarkt V2.pdf (15 x 15 cm)\" title><\/a><\/div><\/div><\/div><\/section><style><\/style><script type=\"text\/javascript\"><\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8059","post","type-post","status-publish","format-standard","hentry","category-allgemein","post-wrapper"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AM_06 - Stark im Norden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AM_06 - Stark im Norden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/\" \/>\n<meta property=\"og:site_name\" content=\"Stark im Norden\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T07:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T07:18:15+00:00\" \/>\n<meta name=\"author\" content=\"stefan_sturm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"stefan_sturm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/\"},\"author\":{\"name\":\"stefan_sturm\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2361b37f7c79cc7218307543887972ce\"},\"headline\":\"AM_06\",\"datePublished\":\"2026-04-28T07:18:12+00:00\",\"dateModified\":\"2026-04-28T07:18:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/\"},\"wordCount\":293,\"publisher\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/\",\"name\":\"AM_06 - Stark im Norden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#website\"},\"datePublished\":\"2026-04-28T07:18:12+00:00\",\"dateModified\":\"2026-04-28T07:18:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/am_06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AM_06\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\",\"name\":\"Stark im Norden\",\"description\":\"QM Alt-Hamborn und Marxloh\",\"publisher\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#organization\",\"name\":\"Stark im Norden\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_03.jpg\",\"contentUrl\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_03.jpg\",\"width\":2000,\"height\":1199,\"caption\":\"Stark im Norden\"},\"image\":{\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/du_starkimnorden\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/2361b37f7c79cc7218307543887972ce\",\"name\":\"stefan_sturm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g\",\"caption\":\"stefan_sturm\"},\"sameAs\":[\"http:\\\/\\\/du-starkimnorden.de\\\/wordpress\"],\"url\":\"https:\\\/\\\/du-starkimnorden.de\\\/wordpress\\\/author\\\/stefan_sturm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AM_06 - Stark im Norden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/","og_locale":"de_DE","og_type":"article","og_title":"AM_06 - Stark im Norden","og_url":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/","og_site_name":"Stark im Norden","article_published_time":"2026-04-28T07:18:12+00:00","article_modified_time":"2026-04-28T07:18:15+00:00","author":"stefan_sturm","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"stefan_sturm","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/#article","isPartOf":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/"},"author":{"name":"stefan_sturm","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/person\/2361b37f7c79cc7218307543887972ce"},"headline":"AM_06","datePublished":"2026-04-28T07:18:12+00:00","dateModified":"2026-04-28T07:18:15+00:00","mainEntityOfPage":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/"},"wordCount":293,"publisher":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#organization"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/","url":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/","name":"AM_06 - Stark im Norden","isPartOf":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#website"},"datePublished":"2026-04-28T07:18:12+00:00","dateModified":"2026-04-28T07:18:15+00:00","breadcrumb":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/du-starkimnorden.de\/wordpress\/am_06\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/du-starkimnorden.de\/wordpress\/am_06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/du-starkimnorden.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"AM_06"}]},{"@type":"WebSite","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#website","url":"https:\/\/du-starkimnorden.de\/wordpress\/","name":"Stark im Norden","description":"QM Alt-Hamborn und Marxloh","publisher":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/du-starkimnorden.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#organization","name":"Stark im Norden","url":"https:\/\/du-starkimnorden.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2023\/04\/Logo_03.jpg","contentUrl":"https:\/\/du-starkimnorden.de\/wordpress\/wp-content\/uploads\/2023\/04\/Logo_03.jpg","width":2000,"height":1199,"caption":"Stark im Norden"},"image":{"@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/du_starkimnorden\/"]},{"@type":"Person","@id":"https:\/\/du-starkimnorden.de\/wordpress\/#\/schema\/person\/2361b37f7c79cc7218307543887972ce","name":"stefan_sturm","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d53a3a69918d41fe53ab37feaafb234d7ca3e8a9cd04459b90c0ab72584d62bc?s=96&d=mm&r=g","caption":"stefan_sturm"},"sameAs":["http:\/\/du-starkimnorden.de\/wordpress"],"url":"https:\/\/du-starkimnorden.de\/wordpress\/author\/stefan_sturm\/"}]}},"_links":{"self":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/posts\/8059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/comments?post=8059"}],"version-history":[{"count":2,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/posts\/8059\/revisions"}],"predecessor-version":[{"id":8061,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/posts\/8059\/revisions\/8061"}],"wp:attachment":[{"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/media?parent=8059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/categories?post=8059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/du-starkimnorden.de\/wordpress\/wp-json\/wp\/v2\/tags?post=8059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}